{"id":32,"count":1,"description":"","link":"https:\/\/ztrategya.com\/en\/category\/desarrollo-web\/","name":"Web development","slug":"desarrollo-web","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desarrollo web Archivos - Ztrategya<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ztrategya.com\/en\/category\/desarrollo-web\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desarrollo web Archivos - Ztrategya\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ztrategya.com\/en\/category\/desarrollo-web\/\" \/>\n<meta property=\"og:site_name\" content=\"Ztrategya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ztrategya.com\\\/category\\\/desarrollo-web\\\/\",\"url\":\"https:\\\/\\\/ztrategya.com\\\/category\\\/desarrollo-web\\\/\",\"name\":\"Desarrollo web Archivos - Ztrategya\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ztrategya.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ztrategya.com\\\/category\\\/desarrollo-web\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ztrategya.com\\\/category\\\/desarrollo-web\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ztrategya.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desarrollo web\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ztrategya.com\\\/#website\",\"url\":\"https:\\\/\\\/ztrategya.com\\\/\",\"name\":\"Ztrategya\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ztrategya.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ztrategya.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ztrategya.com\\\/#organization\",\"name\":\"Ztrategya\",\"url\":\"https:\\\/\\\/ztrategya.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ztrategya.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ztrategya.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-z.svg\",\"contentUrl\":\"https:\\\/\\\/ztrategya.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-z.svg\",\"width\":345.33,\"height\":72.63,\"caption\":\"Ztrategya\"},\"image\":{\"@id\":\"https:\\\/\\\/ztrategya.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desarrollo web Archivos - Ztrategya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ztrategya.com\/en\/category\/desarrollo-web\/","og_locale":"en_US","og_type":"article","og_title":"Desarrollo web Archivos - Ztrategya","og_url":"https:\/\/ztrategya.com\/en\/category\/desarrollo-web\/","og_site_name":"Ztrategya","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ztrategya.com\/category\/desarrollo-web\/","url":"https:\/\/ztrategya.com\/category\/desarrollo-web\/","name":"Desarrollo web Archivos - Ztrategya","isPartOf":{"@id":"https:\/\/ztrategya.com\/#website"},"breadcrumb":{"@id":"https:\/\/ztrategya.com\/category\/desarrollo-web\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ztrategya.com\/category\/desarrollo-web\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ztrategya.com\/"},{"@type":"ListItem","position":2,"name":"Desarrollo web"}]},{"@type":"WebSite","@id":"https:\/\/ztrategya.com\/#website","url":"https:\/\/ztrategya.com\/","name":"Ztrategya","description":"","publisher":{"@id":"https:\/\/ztrategya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ztrategya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ztrategya.com\/#organization","name":"Ztrategya","url":"https:\/\/ztrategya.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ztrategya.com\/#\/schema\/logo\/image\/","url":"https:\/\/ztrategya.com\/wp-content\/uploads\/2023\/03\/logo-z.svg","contentUrl":"https:\/\/ztrategya.com\/wp-content\/uploads\/2023\/03\/logo-z.svg","width":345.33,"height":72.63,"caption":"Ztrategya"},"image":{"@id":"https:\/\/ztrategya.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ztrategya.com\/en\/wp-json\/wp\/v2\/categories\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ztrategya.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ztrategya.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/ztrategya.com\/en\/wp-json\/wp\/v2\/posts?categories=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}